{"id":333,"count":12,"description":"<h1>Basilic<\/h1><p><strong>Ocimum basilicum<\/strong> ou <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/\">basilic<\/a> est une plante herbac\u00e9e annuelle originaire d\u2019Asie du sud ou d\u2019Afrique centrale. Ses feuilles sont utilis\u00e9es comme herbe aromatique en cuisine. Elles sont consomm\u00e9es crues de pr\u00e9f\u00e9rence pour garder tous leurs aromes. Le basilic est tr\u00e8s pr\u00e9sent dans la cuisine m\u00e9diterran\u00e9enne, il rentre dans la composition de la c\u00e9l\u00e8bre soupe au pistou et de la sauce pesto.<\/p><p>Il existe une grande diversit\u00e9 de basilics pour agr\u00e9menter vos plats et diversifier vos recettes avec : <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-grand-vert\/\">Basilic grand vert<\/a>, <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-fin-vert\/\">Basilic fin vert<\/a>, <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-thai\/\">Basilic tha\u00ef<\/a>, <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-pourpre\/\">Basilic pourpre<\/a>, <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-citron-vert\/\">Basilic citron<\/a>, ou encore <a href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/basilic-cannelle-bio\/\">Basilic cannelle.<\/a><\/p><h2>Comment le cuisiner ?<\/h2><p>Avec son profil aromatique distinctif, le basilic devient un \u00e9l\u00e9ment essentiel en cuisine pour rehausser le go\u00fbt de divers plats. Le basilic sera votre meilleur ami pour confectionner un pesto maison. <span style=\"font-size: 1em\">Pr\u00e9parez un m\u00e9lange en pilant d\u00e9licatement les feuilles de basilic avec une pinc\u00e9e de sel, des pignons de pin et de l'ail. Int\u00e9grez ensuite du parmesan r\u00e2p\u00e9 et combinez le tout dans un mixeur avec de l'huile d'olive. <\/span><span style=\"font-size: 1em\">Cette sauce peut sublimer vos p\u00e2tes fra\u00eeches ou agr\u00e9menter votre salade. <\/span><span style=\"font-size: 1em\">Outre le pesto, envisagez d'utiliser les feuilles fra\u00eeches de basilic pour garnir vos pizzas fra\u00eechement sorties du four. Cela ajoutera une note herbac\u00e9e et parfum\u00e9e \u00e0 votre plat.<\/span><\/p><h2>Comment le planter ?<\/h2><p>La culture du basilic, herbac\u00e9e aromatique pris\u00e9e en cuisine, requiert un emplacement ensoleill\u00e9 et un sol bien drain\u00e9, favorisant ainsi une croissance optimale. Les semis peuvent \u00eatre r\u00e9alis\u00e9s \u00e0 l'int\u00e9rieur avant d'\u00eatre transplant\u00e9s en ext\u00e9rieur une fois les risques de gel \u00e9cart\u00e9s, permettant ainsi d'assurer des conditions propices \u00e0 son d\u00e9veloppement.<\/p><h3>emplacement de la culture<\/h3><p>Tout d'abord, choisissez un emplacement bien ensoleill\u00e9. Le basilic prosp\u00e8re dans des conditions de lumi\u00e8re directe pendant au moins six heures par jour, favorisant ainsi une croissance vigoureuse de la plante. Optez pour un sol bien drain\u00e9 et enrichissez-le pr\u00e9alablement avec du compost pour fournir les nutriments essentiels.<\/p><p>Les semis de basilic peuvent \u00eatre r\u00e9alis\u00e9s \u00e0 l'int\u00e9rieur quelques semaines avant la derni\u00e8re date de gel\u00e9e. Par la suite, les plants peuvent \u00eatre transplant\u00e9s \u00e0 l'ext\u00e9rieur. Cette \u00e9tape intervient une fois que tout risque de gel est \u00e9cart\u00e9. Assurez-vous de maintenir une temp\u00e9rature du sol d'au moins 15\u00b0C. Cela favorisera une germination optimale des graines de basilic, assurant ainsi un bon d\u00e9part pour les plants.\u00a0\u00c9claircissez les plants si n\u00e9cessaire, en laissant un espace d'environ 25 \u00e0 30 cm entre chaque pied.<\/p><p>Arrosez r\u00e9guli\u00e8rement, mais \u00e9vitez l'exc\u00e8s d'humidit\u00e9, car le basilic est sensible \u00e0 la pourriture des racines. L'application d'un engrais \u00e9quilibr\u00e9 une fois par mois favorisera une croissance saine. En ce qui concerne la r\u00e9colte, commencez \u00e0 cueillir les feuilles. Il est recommand\u00e9 de le faire lorsque la plante atteint une hauteur d'environ 15 cm. Cela garantit des feuilles de basilic fra\u00eeches et savoureuses, offrant ainsi une exp\u00e9rience culinaire optimale. Veillez \u00e0 couper les tiges juste au-dessus d'une paire de feuilles pour encourager la ramification.<\/p><h3>entretien<\/h3><p>Il est \u00e9galement recommand\u00e9 de proc\u00e9der \u00e0 des \u00e9lagages r\u00e9guliers en pin\u00e7ant les sommit\u00e9s florales. Cette pratique permet de stimuler la production de feuilles. De plus, elle pr\u00e9vient la floraison pr\u00e9coce, favorisant ainsi une croissance plus robuste de la plante de basilic. En fin de saison, avant les premi\u00e8res gel\u00e9es, il peut \u00eatre opportun de r\u00e9colter le basilic restant. Vous pouvez le conserver ou le transformer en pesto, en huile aromatis\u00e9e ou d'autres pr\u00e9parations pour prolonger son utilisation.<\/p><h2>Quels sont les menaces de ravageurs et comment s'en pr\u00e9munir ?<\/h2><h3>les pucerons<\/h3><p>Les pucerons, petits insectes suceurs de s\u00e8ve, peuvent \u00eatre \u00e9loign\u00e9s. Cela peut \u00eatre r\u00e9alis\u00e9 en encourageant la pr\u00e9sence d'insectes auxiliaires tels que les coccinelles et les syrphes, qui sont des pr\u00e9dateurs naturels des pucerons. L'utilisation de solutions insecticides naturelles, comme le savon insecticide, peut \u00e9galement aider \u00e0 contr\u00f4ler les populations de pucerons sans nuire \u00e0 la plante.<\/p><h3>les aleurodes<\/h3><p>Les aleurodes, \u00e9galement connus sous le nom de mouches blanches, sont des insectes volants. Ils peuvent \u00eatre \u00e9loign\u00e9s en maintenant une hygi\u00e8ne du jardin, notamment en \u00e9liminant les mauvaises herbes et les feuilles mortes pour r\u00e9duire les lieux favorables \u00e0 leur reproduction. En \u00e9liminant les mauvaises herbes, les feuilles mortes et en gardant l'environnement propre, vous r\u00e9duirez les endroits propices \u00e0 leur reproduction.<\/p><h3>les limaces<\/h3><p>Les limaces, qui se nourrissent de feuilles, peuvent \u00eatre g\u00e9r\u00e9es en utilisant des barri\u00e8res physiques, telles que des coquilles d'\u0153ufs \u00e9cras\u00e9es ou des paillis. Ces m\u00e9thodes contribuent \u00e0 dissuader les limaces et \u00e0 prot\u00e9ger efficacement les plantes contre les dommages caus\u00e9s par ces ravageurs. L'arrosage au matin plut\u00f4t qu'en soir\u00e9e contribue \u00e0 rendre l'environnement moins attractif pour ces ravageurs. <span class=\"ui-provider ed bau bar bav baw bax bay baz bba bbb bbc bbd bbe bbf bbg bbh bbi bbj bbk bbl bbm bbn bbo bbp bbq bbr bbs bbt bbu bbv bbw bbx bby bbz bca\" dir=\"ltr\">Si n\u00e9cessaire, vous pouvez aussi utiliser du phosphate ferrique en granul\u00e9e pour repousser les limaces.<\/span><\/p>","link":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/","name":"Basilics","slug":"basilic","taxonomy":"product_cat","parent":328,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Graine de basilic | Graines herbes aromatiques | Ernest Turc<\/title>\n<meta name=\"description\" content=\"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Basilics\" \/>\n<meta property=\"og:description\" content=\"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/\" \/>\n<meta property=\"og:site_name\" content=\"Ernest TURC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/aromatiques\\\/basilic\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/aromatiques\\\/basilic\\\/\",\"name\":\"Graine de basilic | Graines herbes aromatiques | Ernest Turc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\"},\"description\":\"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/aromatiques\\\/basilic\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/aromatiques\\\/basilic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graines\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Graines Aromatiques\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/graines\\\/aromatiques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Basilics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"name\":\"Ernest TURC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\",\"name\":\"Boutique Ernest TURC\",\"alternateName\":\"Ernest TURC\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"width\":161,\"height\":161,\"caption\":\"Boutique Ernest TURC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErnestTURC49\",\"https:\\\/\\\/www.instagram.com\\\/ernestturc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ernest-turc\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/ernestturc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH3ntWhy3mdcqw9-xF6pmEQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Graine de basilic | Graines herbes aromatiques | Ernest Turc","description":"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Basilics","og_description":"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.","og_url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/","og_site_name":"Ernest TURC","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/","url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/","name":"Graine de basilic | Graines herbes aromatiques | Ernest Turc","isPartOf":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#website"},"description":"Vente de graines de basilic. Cultiv\u00e9es en France sur nos deux sites de production, nos semences sont \u00e0 destination de tout le monde, professionnel comme particulier.","breadcrumb":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/basilic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ernest-turc.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Graines","item":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/"},{"@type":"ListItem","position":3,"name":"Graines Aromatiques","item":"https:\/\/www.ernest-turc.com\/boutique\/produits\/graines\/aromatiques\/"},{"@type":"ListItem","position":4,"name":"Basilics"}]},{"@type":"WebSite","@id":"https:\/\/www.ernest-turc.com\/boutique\/#website","url":"https:\/\/www.ernest-turc.com\/boutique\/","name":"Ernest TURC","description":"","publisher":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ernest-turc.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization","name":"Boutique Ernest TURC","alternateName":"Ernest TURC","url":"https:\/\/www.ernest-turc.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","width":161,"height":161,"caption":"Boutique Ernest TURC"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErnestTURC49","https:\/\/www.instagram.com\/ernestturc","https:\/\/www.linkedin.com\/company\/ernest-turc\/","https:\/\/www.pinterest.fr\/ernestturc","https:\/\/www.youtube.com\/channel\/UCH3ntWhy3mdcqw9-xF6pmEQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_cat\/333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_cat\/328"}],"wp:post_type":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product?product_cat=333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}