{"id":20584,"date":"2021-07-15T13:14:20","date_gmt":"2021-07-15T13:14:20","guid":{"rendered":"https:\/\/www.ernest-turc.com\/boutique\/produits\/tulipe-triomphe-calgary\/"},"modified":"2025-09-04T14:44:17","modified_gmt":"2025-09-04T14:44:17","slug":"tulipe-triomphe-calgary","status":"publish","type":"product","link":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/","title":{"rendered":"Tulipe Triomphe Calgary"},"content":{"rendered":"<p style=\"text-align: justify\">La tulipe Triomphe Calgary est une jolie bulbeuse de 25 cm de hauteur, qui s&#8217;\u00e9panouit en avril, en d\u00e9voilant une floraison en coupe resserr\u00e9e de 7 cm de diam\u00e8tre, au coloris blanc pur. Avec sa grande tige bien droite, elle sera sublime en massif ou plate-bande, pour cr\u00e9er une tache de couleur spectaculaire ou pour donner de la hauteur de mani\u00e8re plus diffuse et naturelle \u00e0 une composition de vivaces de printemps ou de bisannuelles. En grand pot, elle sublimera vos balcons et terrasses en association avec d&#8217;autres bulbeuses \u00e0 floraison printani\u00e8re comme les muscaris ou les narcisses grande coupe. En vase, cette tulipe Triomphe fera entrer une note de fraicheur printani\u00e8re dans votre int\u00e9rieur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify\">La tulipe Triomphe Calgary est une jolie bulbeuse de 25 cm de hauteur, qui s&#8217;\u00e9panouit en avril, en d\u00e9voilant une floraison en coupe resserr\u00e9e de 7 cm de diam\u00e8tre, au coloris blanc pur.<\/p>\n","protected":false},"featured_media":20586,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[179,180,212,1726,1591,1541,182,1731,1722],"product_tag":[],"class_list":{"0":"post-20584","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bulbes","7":"product_cat-fleurs","8":"product_cat-theme","9":"product_cat-fleurs-simples-tulipes","10":"product_cat-plante-pot","11":"product_cat-printemps","12":"product_cat-saison","13":"product_cat-triomphes","14":"product_cat-tulipes","15":"pa_calibre-89","16":"pa_conditionnement-1475","17":"pa_couleur-blanc","18":"pa_couleur-de-feuillage-vert","19":"pa_disponibilite-de-septembre-a-decembre","20":"pa_exposition-ensoleillee","21":"pa_exposition-mi-ensoleillee","22":"pa_hauteur-de-la-plante-25-cm","23":"pa_periode-de-recolte-floraison-avril","24":"pa_periode-de-semis-plantation-decembre","25":"pa_periode-de-semis-plantation-novembre","26":"pa_periode-de-semis-plantation-octobre","27":"pa_periode-de-semis-plantation-septembre","28":"pa_rusticite-rustique","29":"pa_utilisation-fleur-coupee","30":"pa_utilisation-massif","31":"pa_utilisation-pot","33":"first","34":"outofstock","35":"taxable","36":"shipping-taxable","37":"purchasable","38":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tulipe Triomphe Calgary - Ernest TURC<\/title>\n<meta name=\"description\" content=\"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tulipe Triomphe Calgary\" \/>\n<meta property=\"og:description\" content=\"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/\" \/>\n<meta property=\"og:site_name\" content=\"Ernest TURC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErnestTURC49\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T14:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-triomphe-calgary.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"110,00&euro;TTCTTC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/\",\"name\":\"Tulipe Triomphe Calgary - Ernest TURC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-triomphe-calgary.jpg\",\"datePublished\":\"2021-07-15T13:14:20+00:00\",\"dateModified\":\"2025-09-04T14:44:17+00:00\",\"description\":\"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-triomphe-calgary.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-triomphe-calgary.jpg\",\"width\":800,\"height\":800,\"caption\":\"Tulipe Triomphe Calgary\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/triomphes\\\/tulipe-triomphe-calgary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.ernest-turc.fr\\\/boutique\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tulipe Triomphe Calgary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"name\":\"Ernest TURC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\",\"name\":\"Boutique Ernest TURC\",\"alternateName\":\"Ernest TURC\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"width\":161,\"height\":161,\"caption\":\"Boutique Ernest TURC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErnestTURC49\",\"https:\\\/\\\/www.instagram.com\\\/ernestturc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ernest-turc\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/ernestturc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH3ntWhy3mdcqw9-xF6pmEQ\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"110.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"115590-6\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tulipe Triomphe Calgary - Ernest TURC","description":"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/","og_locale":"fr_FR","og_type":"article","og_title":"Tulipe Triomphe Calgary","og_description":"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.","og_url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/","og_site_name":"Ernest TURC","article_publisher":"https:\/\/www.facebook.com\/ErnestTURC49","article_modified_time":"2025-09-04T14:44:17+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-triomphe-calgary.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"110,00&euro;TTCTTC","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/","url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/","name":"Tulipe Triomphe Calgary - Ernest TURC","isPartOf":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/#primaryimage"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-triomphe-calgary.jpg","datePublished":"2021-07-15T13:14:20+00:00","dateModified":"2025-09-04T14:44:17+00:00","description":"Tulipe Triomphe Calgary \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection de Triomphes pour sublimer vos jardins.","breadcrumb":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/#primaryimage","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-triomphe-calgary.jpg","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-triomphe-calgary.jpg","width":800,"height":800,"caption":"Tulipe Triomphe Calgary"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/triomphes\/tulipe-triomphe-calgary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ernest-turc.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.ernest-turc.fr\/boutique\/produits\/"},{"@type":"ListItem","position":3,"name":"Tulipe Triomphe Calgary"}]},{"@type":"WebSite","@id":"https:\/\/www.ernest-turc.com\/boutique\/#website","url":"https:\/\/www.ernest-turc.com\/boutique\/","name":"Ernest TURC","description":"","publisher":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ernest-turc.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization","name":"Boutique Ernest TURC","alternateName":"Ernest TURC","url":"https:\/\/www.ernest-turc.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","width":161,"height":161,"caption":"Boutique Ernest TURC"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErnestTURC49","https:\/\/www.instagram.com\/ernestturc","https:\/\/www.linkedin.com\/company\/ernest-turc\/","https:\/\/www.pinterest.fr\/ernestturc","https:\/\/www.youtube.com\/channel\/UCH3ntWhy3mdcqw9-xF6pmEQ"]}]},"product_price_amount":"110.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"115590-6","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product\/20584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media\/20586"}],"wp:attachment":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media?parent=20584"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_brand?post=20584"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_cat?post=20584"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_tag?post=20584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}