{"id":19742,"date":"2021-07-15T12:56:08","date_gmt":"2021-07-15T12:56:08","guid":{"rendered":"https:\/\/www.ernest-turc.com\/boutique\/produits\/tulipe-dentelle-curly-sue\/"},"modified":"2026-05-12T16:24:31","modified_gmt":"2026-05-12T16:24:31","slug":"tulipe-dentelle-curly-sue","status":"publish","type":"product","link":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/","title":{"rendered":"Tulipe Dentelle Curly Sue"},"content":{"rendered":"<p style=\"text-align: justify;\">La tulipe dentelle Curly Sue est une bulbeuse \u00e9l\u00e9gante et originale de 45 cm de hauteur qui s&#8217;\u00e9panouit fin avril d\u00e9but mai, en d\u00e9voilant une floraison aux p\u00e9tales cisel\u00e9s de 7 cm de diam\u00e8tre, au coloris violet pourpr\u00e9 intense. Avec sa forme d\u00e9coup\u00e9e, elle sera sublime en massif ou plate-bande, pour cr\u00e9er une tache de couleur spectaculaire ou pour donner de la hauteur de mani\u00e8re plus diffuse et naturelle \u00e0 une composition de vivaces de printemps ou de bisannuelles. En grand pot ou bac, elle sublimera vos balcons et terrasses en association avec d&#8217;autres bulbeuses \u00e0 floraison printani\u00e8re comme les narcisses \u00e0 grande coupe ou les an\u00e9mones blanda. En vase, cette tulipe dentelle fera entrer une note sophistiqu\u00e9e et chic dans votre int\u00e9rieur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">La tulipe dentelle Curly Sue est une bulbeuse \u00e9l\u00e9gante et originale de 45 cm de hauteur qui s&#8217;\u00e9panouit fin avril d\u00e9but mai, en d\u00e9voilant une floraison aux p\u00e9tales cisel\u00e9s de 7 cm de diam\u00e8tre, au coloris violet pourpr\u00e9 intense.<\/p>\n","protected":false},"featured_media":19744,"template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[],"product_cat":[1609,179,180,212,1726,2229,1541,182,1728,1722],"product_tag":[2627,2350,1911,2629,2575],"class_list":{"0":"post-19742","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bouquets","7":"product_cat-bulbes","8":"product_cat-fleurs","9":"product_cat-theme","10":"product_cat-fleurs-simples-tulipes","11":"product_cat-fleurs-violettes","12":"product_cat-printemps","13":"product_cat-saison","14":"product_cat-tardives","15":"product_cat-tulipes","16":"product_tag-fleur-frangee","17":"product_tag-fleur-pourpre","18":"product_tag-tulipe-dentelle","19":"product_tag-tulipe-frengee","20":"product_tag-tulipe-pourpre","21":"pa_calibre-11-12","22":"pa_conditionnement-1475","23":"pa_conditionnement-2515","24":"pa_couleur-violet","25":"pa_couleur-de-feuillage-vert","26":"pa_disponibilite-de-septembre-a-decembre","27":"pa_exposition-ensoleillee","28":"pa_exposition-mi-ensoleillee","29":"pa_hauteur-de-la-plante-45-cm","30":"pa_periode-de-recolte-floraison-avril","31":"pa_periode-de-recolte-floraison-mai","32":"pa_periode-de-semis-plantation-decembre","33":"pa_periode-de-semis-plantation-novembre","34":"pa_periode-de-semis-plantation-octobre","35":"pa_periode-de-semis-plantation-septembre","36":"pa_rusticite-rustique","37":"pa_utilisation-fleur-coupee","38":"pa_utilisation-massif","40":"first","41":"outofstock","42":"taxable","43":"shipping-taxable","44":"purchasable","45":"product-type-variable"},"bundled_by":["28863"],"bundle_stock_status":"outofstock","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tulipe Dentelle Curly Sue - Ernest TURC<\/title>\n<meta name=\"description\" content=\"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tulipe Dentelle Curly Sue\" \/>\n<meta property=\"og:description\" content=\"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/\" \/>\n<meta property=\"og:site_name\" content=\"Ernest TURC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErnestTURC49\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-dentelle-curly-sue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/\",\"name\":\"Tulipe Dentelle Curly Sue - Ernest TURC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-dentelle-curly-sue.jpg\",\"datePublished\":\"2021-07-15T12:56:08+00:00\",\"dateModified\":\"2026-05-12T16:24:31+00:00\",\"description\":\"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-dentelle-curly-sue.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/tulipe-dentelle-curly-sue.jpg\",\"width\":800,\"height\":800,\"caption\":\"Tulipe Dentelle Curly Sue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/produits\\\/bulbes\\\/fleurs\\\/tulipes\\\/fleurs-simples-tulipes\\\/tulipe-dentelle-curly-sue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/www.ernest-turc.fr\\\/boutique\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tulipe Dentelle Curly Sue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"name\":\"Ernest TURC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\",\"name\":\"Boutique Ernest TURC\",\"alternateName\":\"Ernest TURC\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"width\":161,\"height\":161,\"caption\":\"Boutique Ernest TURC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErnestTURC49\",\"https:\\\/\\\/www.instagram.com\\\/ernestturc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ernest-turc\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/ernestturc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH3ntWhy3mdcqw9-xF6pmEQ\"]}]}<\/script>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"953929\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tulipe Dentelle Curly Sue - Ernest TURC","description":"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/","og_locale":"fr_FR","og_type":"article","og_title":"Tulipe Dentelle Curly Sue","og_description":"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.","og_url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/","og_site_name":"Ernest TURC","article_publisher":"https:\/\/www.facebook.com\/ErnestTURC49","article_modified_time":"2026-05-12T16:24:31+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-dentelle-curly-sue.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/","url":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/","name":"Tulipe Dentelle Curly Sue - Ernest TURC","isPartOf":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/#primaryimage"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-dentelle-curly-sue.jpg","datePublished":"2021-07-15T12:56:08+00:00","dateModified":"2026-05-12T16:24:31+00:00","description":"Tulipe Dentelle Curly Sue \u00e0 acheter en ligne avec Ernest Turc, producteur de bulbes et de graines. D\u00e9couvrez notre s\u00e9lection pour sublimer vos jardins.","breadcrumb":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/#primaryimage","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-dentelle-curly-sue.jpg","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2021\/07\/tulipe-dentelle-curly-sue.jpg","width":800,"height":800,"caption":"Tulipe Dentelle Curly Sue"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ernest-turc.com\/boutique\/produits\/bulbes\/fleurs\/tulipes\/fleurs-simples-tulipes\/tulipe-dentelle-curly-sue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ernest-turc.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/www.ernest-turc.fr\/boutique\/produits\/"},{"@type":"ListItem","position":3,"name":"Tulipe Dentelle Curly Sue"}]},{"@type":"WebSite","@id":"https:\/\/www.ernest-turc.com\/boutique\/#website","url":"https:\/\/www.ernest-turc.com\/boutique\/","name":"Ernest TURC","description":"","publisher":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ernest-turc.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization","name":"Boutique Ernest TURC","alternateName":"Ernest TURC","url":"https:\/\/www.ernest-turc.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","width":161,"height":161,"caption":"Boutique Ernest TURC"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErnestTURC49","https:\/\/www.instagram.com\/ernestturc","https:\/\/www.linkedin.com\/company\/ernest-turc\/","https:\/\/www.pinterest.fr\/ernestturc","https:\/\/www.youtube.com\/channel\/UCH3ntWhy3mdcqw9-xF6pmEQ"]}]},"og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"953929","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product\/19742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media\/19744"}],"wp:attachment":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media?parent=19742"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_brand?post=19742"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_cat?post=19742"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/product_tag?post=19742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}