{"id":29539,"date":"2023-11-30T09:54:19","date_gmt":"2023-11-30T09:54:19","guid":{"rendered":"https:\/\/www.ernest-turc.fr\/boutique\/?p=29539"},"modified":"2024-12-17T15:42:05","modified_gmt":"2024-12-17T15:42:05","slug":"agapanthes-plantation-et-conseils-de-culture","status":"publish","type":"post","link":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/","title":{"rendered":"Agapanthes : Plantation et conseils de culture"},"content":{"rendered":"<div id=\"pl-29539\"  class=\"panel-layout\" ><div id=\"pg-29539-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-29539-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-29539-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h1 style=\"text-align: center;\">Agapanthe, une vivace bien connue !<\/h1>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-0-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-29539\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe.jpg\" width=\"1920\" height=\"473\" srcset=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe.jpg 1920w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-300x74.jpg 300w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-1024x252.jpg 1024w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-768x189.jpg 768w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-1536x378.jpg 1536w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-395x97.jpg 395w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-512x126.jpg 512w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-500x123.jpg 500w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/bandeau-agapanthe-64x16.jpg 64w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-29539-0-0-2\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Les agapanthes sont des plantes faciles \u00e0 vivre qui apportent une touche <strong>exotique<\/strong> et <strong>gracieuse<\/strong> \u00e0 votre jardin ou terrasse. En leur offrant du <strong>soleil<\/strong>, un <strong>sol drain\u00e9<\/strong>, et quelques soins adapt\u00e9s, elles vous r\u00e9compenseront par une floraison spectaculaire tout l'\u00e9t\u00e9.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-29539-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-29539-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-29539-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2><strong>Comment planter des agapanthes ?<\/strong><\/h2>\n<p>Privil\u00e9gier un endroit bien ensoleill\u00e9 du jardin. Les agapanthes ont besoin de beaucoup de soleil pour bien fleurir. Elles se plaisent dans tout type de sol bien drainant car elles n\u2019aiment pas avoir de l\u2019eau stagnante autour de leurs racines. Elles seront l\u00e0 pour de nombreuses ann\u00e9es et pourront former une touffe assez imposante.<br \/>\nDans les r\u00e9gions o\u00f9 les hivers sont vraiment froids, ou si votre sol a tendance \u00e0 \u00eatre gorg\u00e9 d\u2019eau en hiver, il sera pr\u00e9f\u00e9rable d\u2019opter pour une culture en pot qui lui conviendra tr\u00e8s bien \u00e9galement.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-29539-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-29539-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-29539-2-0-0\" class=\"so-panel widget widget_sow-image panel-first-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-29539\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-blanche.jpg\" width=\"450\" height=\"400\" srcset=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-blanche.jpg 450w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-blanche-300x267.jpg 300w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-blanche-347x308.jpg 347w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-blanche-64x57.jpg 64w\" sizes=\"(max-width: 450px) 100vw, 450px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-29539-2-0-1\" class=\"so-panel widget widget_sow-image\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-29539\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/massif-agapanthus.jpg\" width=\"450\" height=\"400\" srcset=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/massif-agapanthus.jpg 450w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/massif-agapanthus-300x267.jpg 300w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/massif-agapanthus-347x308.jpg 347w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/massif-agapanthus-64x57.jpg 64w\" sizes=\"(max-width: 450px) 100vw, 450px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><div id=\"panel-29539-2-0-2\" class=\"so-panel widget widget_sow-image panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-8b5b6f678277-29539\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-bleue.jpg\" width=\"450\" height=\"400\" srcset=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-bleue.jpg 450w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-bleue-300x267.jpg 300w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-bleue-347x308.jpg 347w, https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/agapanthe-bleue-64x57.jpg 64w\" sizes=\"(max-width: 450px) 100vw, 450px\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-29539-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-29539-2-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: justify;\"><strong>Comment pr\u00e9parer son sol pour l'agapanthe ?<\/strong><\/h3>\n<p>Travailler le sol en profondeur et supprimer les r\u00e9sidus de racines. Si votre terre est trop lourde et peu drainante, m\u00e9langer du sable et du terreau \u00e0 la terre dans le trou de plantation.<br \/>\nL\u2019agapanthe a un syst\u00e8me racinaire tr\u00e8s puissant. Plus ce dernier est contraint et serr\u00e9 dans son environnement, plus la plante aura tendance \u00e0 produire des fleurs. En pleine terre, si votre agapanthe ne fleurit pas assez, il est possible d\u2019enserrer le syst\u00e8me racinaire en l\u2019encerclant avec des cailloux ou du gravier grossier.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-2-1-1\" class=\"so-panel widget widget_sow-editor\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: justify;\">Quand planter les racines d'agapanthe ?<\/h3>\n<p style=\"text-align: justify;\">La meilleure p\u00e9riode de plantation des agapanthes est au printemps, mais il est \u00e9galement possible de les planter \u00e0 l\u2019automne, en prenant le soin de bien les prot\u00e9ger pour leur premier hiver en terre.<br \/>\nFaire un trou de plantation assez large et profond, et positionner les souches, d\u00e9parts de tige apparents vers le haut, de mani\u00e8re \u00e0 laisser 10 \u00e0 15 cm de terre au-dessus des bourgeons. Une plantation assez profonde pourra mieux les isoler du gel dans les r\u00e9gions froides.<br \/>\nAyant un fort potentiel de d\u00e9veloppement, maintenir une distance de plantation de 60 \u00e0 70 cm environ.<br \/>\nArroser copieusement apr\u00e8s la plantation pour favoriser la bonne adh\u00e9rence de la terre autour des racines, et r\u00e9guli\u00e8rement jusqu\u2019\u00e0 la reprise, surtout si la plantation a eu lieu au printemps.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-2-1-2\" class=\"so-panel widget widget_sow-editor\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3><strong>Arrosage et fertilisation<\/strong><\/h3>\n<p style=\"text-align: justify;\">Il est possible de faire un apport annuel d\u2019engrais organique, mais cela n\u2019est pas indispensable.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-2-1-3\" class=\"so-panel widget widget_sow-editor\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3><strong>Entretien de l'agapanthe<\/strong><\/h3>\n<p style=\"text-align: justify;\">La premi\u00e8re ann\u00e9e, arroser la souche en p\u00e9riode estivale.<br \/>\nCouper les fleurs fan\u00e9es pour \u00e9viter la formation de fruits et de graines qui \u00e9puisent la plante.<br \/>\nCouper le feuillage une fois celui-ci totalement fan\u00e9 et supprimer tous les d\u00e9chets de culture pour \u00e9viter le d\u00e9veloppement de pourriture.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-2-1-4\" class=\"so-panel widget widget_sow-editor\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3><strong>Ravageurs et maladies des agapanthes<\/strong><\/h3>\n<p style=\"text-align: justify;\">Les agapanthes ne sont pas sensibles \u00e0 des ravageurs particuliers.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-29539-2-1-5\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3><strong>Comment conserver ses agapanthes en hiver ?<\/strong><\/h3>\n<h4><strong>Hivernage<\/strong><\/h4>\n<p style=\"text-align: justify;\">Les agapanthes sont plus ou moins rustiques selon les esp\u00e8ces. Les vari\u00e9t\u00e9s \u00e0 feuillages persistants supportent des gels l\u00e9gers ne d\u00e9passant pas les -5\u00b0C. Selon les r\u00e9gions froides, un <strong>\u00e9pais paillage<\/strong> est indispensable pour leur permettre de passer l\u2019hiver en terre. Les vari\u00e9t\u00e9s \u00e0 feuillage caduque sont quant \u00e0 elles plus rustiques et supportent en g\u00e9n\u00e9ral des gels jusqu\u2019\u00e0 -15\u00b0C.<br \/>\nEn pot, hiverner les agapanthes en cas de gel.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Agapanthe, une vivace bien connue ! Les agapanthes sont des plantes faciles \u00e0 vivre qui apportent une touche exotique et gracieuse \u00e0 votre jardin ou terrasse. En leur offrant [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":35567,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1,1790],"tags":[2134,2133,2122,2124,2131,2132,2130,2127,2126,2123,2128,2125,2129],"class_list":["post-29539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-de-culture","category-conseils-par-famille","tag-agapanthe-blanche","tag-agapanthe-bleue","tag-agapanthe-en-pot","tag-agapanthe-entretien","tag-agapanthe-pot","tag-agapanthe-rose","tag-agapanthe-vivace","tag-agapanthus","tag-culture-agapanthe","tag-fleur-agapanthe","tag-floraison-agapanthe","tag-plantation-agapanthe","tag-plante-agapanthe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bulbes \u00e0 floraison printani\u00e8re: conseils pour les choisir - Ernest TURC<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les atouts des bulbes \u00e0 floraison printani\u00e8re, tels que les agapanthes, ornithogalum, eremurus, camassias, scilles et chionodoxas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agapanthes : Plantation et conseils de culture\" \/>\n<meta property=\"og:description\" content=\"Ernest TURC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/\" \/>\n<meta property=\"og:site_name\" content=\"Ernest TURC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ErnestTURC49\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T09:54:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T15:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah Leclaire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Leclaire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/\"},\"author\":{\"name\":\"Sarah Leclaire\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b513eb02eecb557b7d53cffb95f86d4e\"},\"headline\":\"Agapanthes : Plantation et conseils de culture\",\"datePublished\":\"2023-11-30T09:54:19+00:00\",\"dateModified\":\"2024-12-17T15:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/\"},\"wordCount\":606,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/visuel-agapanthe.jpg\",\"keywords\":[\"agapanthe blanche\",\"agapanthe bleue\",\"agapanthe en pot\",\"agapanthe entretien\",\"agapanthe pot\",\"agapanthe rose\",\"agapanthe vivace\",\"agapanthus\",\"culture agapanthe\",\"fleur agapanthe\",\"floraison agapanthe\",\"plantation agapanthe\",\"plante agapanthe\"],\"articleSection\":[\"Conseils de culture\",\"Conseils par famille de produits\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/\",\"name\":\"Bulbes \u00e0 floraison printani\u00e8re: conseils pour les choisir - Ernest TURC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/visuel-agapanthe.jpg\",\"datePublished\":\"2023-11-30T09:54:19+00:00\",\"dateModified\":\"2024-12-17T15:42:05+00:00\",\"description\":\"D\u00e9couvrez les atouts des bulbes \u00e0 floraison printani\u00e8re, tels que les agapanthes, ornithogalum, eremurus, camassias, scilles et chionodoxas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/visuel-agapanthe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/visuel-agapanthe.jpg\",\"width\":627,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/conseils-de-culture\\\/conseils-par-famille\\\/agapanthes-plantation-et-conseils-de-culture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agapanthes : Plantation et conseils de culture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"name\":\"Ernest TURC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#organization\",\"name\":\"Boutique Ernest TURC\",\"alternateName\":\"Ernest TURC\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo.png\",\"width\":161,\"height\":161,\"caption\":\"Boutique Ernest TURC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ErnestTURC49\",\"https:\\\/\\\/www.instagram.com\\\/ernestturc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ernest-turc\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/ernestturc\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH3ntWhy3mdcqw9-xF6pmEQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ernest-turc.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b513eb02eecb557b7d53cffb95f86d4e\",\"name\":\"Sarah Leclaire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g\",\"caption\":\"Sarah Leclaire\"},\"sameAs\":[\"http:\\\/\\\/netconcept\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bulbes \u00e0 floraison printani\u00e8re: conseils pour les choisir - Ernest TURC","description":"D\u00e9couvrez les atouts des bulbes \u00e0 floraison printani\u00e8re, tels que les agapanthes, ornithogalum, eremurus, camassias, scilles et chionodoxas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/","og_locale":"fr_FR","og_type":"article","og_title":"Agapanthes : Plantation et conseils de culture","og_description":"Ernest TURC","og_url":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/","og_site_name":"Ernest TURC","article_publisher":"https:\/\/www.facebook.com\/ErnestTURC49","article_published_time":"2023-11-30T09:54:19+00:00","article_modified_time":"2024-12-17T15:42:05+00:00","og_image":[{"width":627,"height":378,"url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg","type":"image\/jpeg"}],"author":"Sarah Leclaire","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sarah Leclaire","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#article","isPartOf":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/"},"author":{"name":"Sarah Leclaire","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/person\/b513eb02eecb557b7d53cffb95f86d4e"},"headline":"Agapanthes : Plantation et conseils de culture","datePublished":"2023-11-30T09:54:19+00:00","dateModified":"2024-12-17T15:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/"},"wordCount":606,"publisher":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg","keywords":["agapanthe blanche","agapanthe bleue","agapanthe en pot","agapanthe entretien","agapanthe pot","agapanthe rose","agapanthe vivace","agapanthus","culture agapanthe","fleur agapanthe","floraison agapanthe","plantation agapanthe","plante agapanthe"],"articleSection":["Conseils de culture","Conseils par famille de produits"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/","url":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/","name":"Bulbes \u00e0 floraison printani\u00e8re: conseils pour les choisir - Ernest TURC","isPartOf":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#primaryimage"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg","datePublished":"2023-11-30T09:54:19+00:00","dateModified":"2024-12-17T15:42:05+00:00","description":"D\u00e9couvrez les atouts des bulbes \u00e0 floraison printani\u00e8re, tels que les agapanthes, ornithogalum, eremurus, camassias, scilles et chionodoxas.","breadcrumb":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#primaryimage","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2023\/11\/visuel-agapanthe.jpg","width":627,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/www.ernest-turc.com\/boutique\/conseils-de-culture\/conseils-par-famille\/agapanthes-plantation-et-conseils-de-culture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ernest-turc.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Agapanthes : Plantation et conseils de culture"}]},{"@type":"WebSite","@id":"https:\/\/www.ernest-turc.com\/boutique\/#website","url":"https:\/\/www.ernest-turc.com\/boutique\/","name":"Ernest TURC","description":"","publisher":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ernest-turc.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ernest-turc.com\/boutique\/#organization","name":"Boutique Ernest TURC","alternateName":"Ernest TURC","url":"https:\/\/www.ernest-turc.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.ernest-turc.com\/boutique\/wp-content\/uploads\/2020\/10\/logo.png","width":161,"height":161,"caption":"Boutique Ernest TURC"},"image":{"@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ErnestTURC49","https:\/\/www.instagram.com\/ernestturc","https:\/\/www.linkedin.com\/company\/ernest-turc\/","https:\/\/www.pinterest.fr\/ernestturc","https:\/\/www.youtube.com\/channel\/UCH3ntWhy3mdcqw9-xF6pmEQ"]},{"@type":"Person","@id":"https:\/\/www.ernest-turc.com\/boutique\/#\/schema\/person\/b513eb02eecb557b7d53cffb95f86d4e","name":"Sarah Leclaire","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e0ea8dc3b7bc38202fd91fcabc82c78ae39c29e8a93a87b869ca37a876cbf55?s=96&d=mm&r=g","caption":"Sarah Leclaire"},"sameAs":["http:\/\/netconcept"]}]}},"_links":{"self":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/posts\/29539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/comments?post=29539"}],"version-history":[{"count":5,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/posts\/29539\/revisions"}],"predecessor-version":[{"id":35574,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/posts\/29539\/revisions\/35574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media\/35567"}],"wp:attachment":[{"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/media?parent=29539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/categories?post=29539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ernest-turc.com\/boutique\/wp-json\/wp\/v2\/tags?post=29539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}